{"id":5853,"date":"2025-04-24T14:49:28","date_gmt":"2025-04-24T12:49:28","guid":{"rendered":"https:\/\/olijfboom-shop.be\/?post_type=product&#038;p=5853"},"modified":"2026-04-04T15:40:17","modified_gmt":"2026-04-04T13:40:17","slug":"adoption-de-lolivier-80p","status":"publish","type":"product","link":"https:\/\/olijfboom-shop.be\/fr\/acheter\/adoption-de-lolivier-80p\/","title":{"rendered":"Olijfboom adoptie 80p"},"content":{"rendered":"<p><strong>Olijfboom adoptie 80p<\/strong><\/p>\n<p><strong>Adoptez maintenant un olivier unique pour 1 an sous la forme d'un abonnement \u00e0 l'huile d'olive extra vierge.<\/strong><\/p>\n<p>Vous adoptez un olivier de l'oliveraie traditionnelle de Sabor el Olivar, sous la forme de 2 x 500 lm d'huile d'olive extra vierge de premi\u00e8re qualit\u00e9.<\/p>\n<p>L'oliveraie est situ\u00e9e \u00e0 Torrebesses de Lleida en Espagne.<\/p>\n<p>L'oliveraie de Sabor el Olivar est aliment\u00e9e par la pluie, c'est-\u00e0-dire qu'elle d\u00e9pend des pr\u00e9cipitations, lesquelles sont n\u00e9cessaires \u00e0 la nouaison et au d\u00e9veloppement de l'olive. L'oliveraie est \u00e9galement exempte de pesticides et d'engrais chimiques et\/ou synth\u00e9tiques. Comme l'oliveraie est exempte de produits chimiques, on y trouve beaucoup de vie bio-diversifi\u00e9e, tant des plantes que des animaux et des insectes b\u00e9n\u00e9fiques. C'est pourquoi, <strong>Olijfboom adoptie 80p <\/strong>un excellent choix.<\/p>\n<ul>\n<li>Hors frais d'exp\u00e9dition \u00e9ventuels.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<h5><strong>Olijfboom adoptie 80p<\/strong><\/h5>\n<p><strong>Adoptez maintenant un olivier Unique pour 1 an sous la forme d'un abonnement \u00e0 l'huile d'olive extra vierge.<\/strong><\/p>\n<p>Sous la forme de 2 x 500 lm d'huile d'olive extra vierge de premi\u00e8re qualit\u00e9.<\/p>\n<ul>\n<li>Hors frais d'exp\u00e9dition \u00e9ventuels<\/li>\n<\/ul>","protected":false},"featured_media":5843,"template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[75],"product_cat":[83],"product_tag":[84],"giftcard-category":[],"class_list":["post-5853","product","type-product","status-publish","has-post-thumbnail","product_brand-old-special-trees","product_cat-olijfboom-adoptie","product_tag-olijfbomen","first","instock","virtual","taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/olijfboom-shop.be\/fr\/wp-json\/wp\/v2\/product\/5853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olijfboom-shop.be\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/olijfboom-shop.be\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olijfboom-shop.be\/fr\/wp-json\/wp\/v2\/media\/5843"}],"wp:attachment":[{"href":"https:\/\/olijfboom-shop.be\/fr\/wp-json\/wp\/v2\/media?parent=5853"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/olijfboom-shop.be\/fr\/wp-json\/wp\/v2\/product_brand?post=5853"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/olijfboom-shop.be\/fr\/wp-json\/wp\/v2\/product_cat?post=5853"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/olijfboom-shop.be\/fr\/wp-json\/wp\/v2\/product_tag?post=5853"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/olijfboom-shop.be\/fr\/wp-json\/wp\/v2\/giftcard-category?post=5853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}